{"id":19898,"date":"2020-10-23T14:17:19","date_gmt":"2020-10-23T20:17:19","guid":{"rendered":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12.jpg"},"modified":"2020-10-23T14:17:19","modified_gmt":"2020-10-23T20:17:19","slug":"reconocimiento-25-servicio-igss-2020-12","status":"inherit","type":"attachment","link":"https:\/\/www.igssgt.org\/noticias\/reconocimiento-25-servicio-igss-2020-12\/","title":{"rendered":"Reconocimiento 25 servicio IGSS 2020-12"},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-19898","attachment","type-attachment","status-inherit"],"description":{"rendered":"<p class=\"attachment\"><a href='\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"165\" src=\"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12-300x165.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12-300x165.jpg 300w, \/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12-768x423.jpg 768w, \/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12-762x420.jpg 762w, \/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12-696x385.jpg 696w, \/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12-534x294.jpg 534w, \/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12.jpg 904w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":904,"height":498,"file":"2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12.jpg","filesize":95436,"sizes":{"td_485x360":{"file":"Reconocimiento-25-servicio-IGSS-2020-12-485x360.jpg","width":485,"height":360,"filesize":31635,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12-485x360.jpg"},"thumbnail":{"file":"Reconocimiento-25-servicio-IGSS-2020-12-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12-150x150.jpg"},"medium":{"file":"Reconocimiento-25-servicio-IGSS-2020-12-300x165.jpg","width":300,"height":165,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12-300x165.jpg"},"medium_large":{"file":"Reconocimiento-25-servicio-IGSS-2020-12-768x423.jpg","width":768,"height":423,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12-768x423.jpg"},"td_0x420":{"file":"Reconocimiento-25-servicio-IGSS-2020-12-762x420.jpg","width":762,"height":420,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12-762x420.jpg"},"td_80x60":{"file":"Reconocimiento-25-servicio-IGSS-2020-12-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12-80x60.jpg"},"td_218x150":{"file":"Reconocimiento-25-servicio-IGSS-2020-12-218x150.jpg","width":218,"height":150,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12-218x150.jpg"},"td_324x400":{"file":"Reconocimiento-25-servicio-IGSS-2020-12-324x400.jpg","width":324,"height":400,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12-324x400.jpg"},"td_696x0":{"file":"Reconocimiento-25-servicio-IGSS-2020-12-696x383.jpg","width":696,"height":383,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12-696x383.jpg"},"td_100x70":{"file":"Reconocimiento-25-servicio-IGSS-2020-12-100x70.jpg","width":100,"height":70,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12-100x70.jpg"},"td_265x198":{"file":"Reconocimiento-25-servicio-IGSS-2020-12-265x198.jpg","width":265,"height":198,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12-265x198.jpg"},"td_324x160":{"file":"Reconocimiento-25-servicio-IGSS-2020-12-324x160.jpg","width":324,"height":160,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12-324x160.jpg"},"td_324x235":{"file":"Reconocimiento-25-servicio-IGSS-2020-12-324x235.jpg","width":324,"height":235,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12-324x235.jpg"},"td_356x220":{"file":"Reconocimiento-25-servicio-IGSS-2020-12-356x220.jpg","width":356,"height":220,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12-356x220.jpg"},"td_356x364":{"file":"Reconocimiento-25-servicio-IGSS-2020-12-356x364.jpg","width":356,"height":364,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12-356x364.jpg"},"td_533x261":{"file":"Reconocimiento-25-servicio-IGSS-2020-12-533x261.jpg","width":533,"height":261,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12-533x261.jpg"},"td_534x462":{"file":"Reconocimiento-25-servicio-IGSS-2020-12-534x294.jpg","width":534,"height":294,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12-534x294.jpg"},"td_696x385":{"file":"Reconocimiento-25-servicio-IGSS-2020-12-696x385.jpg","width":696,"height":385,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12-696x385.jpg"},"td_741x486":{"file":"Reconocimiento-25-servicio-IGSS-2020-12-741x486.jpg","width":741,"height":486,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12-741x486.jpg"},"carrusel-slider":{"file":"Reconocimiento-25-servicio-IGSS-2020-12-500x440.jpg","width":500,"height":440,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12-500x440.jpg"},"full":{"file":"Reconocimiento-25-servicio-IGSS-2020-12.jpg","width":904,"height":498,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-12.jpg","_links":{"self":[{"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/media\/19898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/comments?post=19898"}]}}