{"id":19909,"date":"2020-10-23T14:18:02","date_gmt":"2020-10-23T20:18:02","guid":{"rendered":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23.jpg"},"modified":"2020-10-23T14:18:02","modified_gmt":"2020-10-23T20:18:02","slug":"reconocimiento-25-servicio-igss-2020-23","status":"inherit","type":"attachment","link":"https:\/\/www.igssgt.org\/noticias\/reconocimiento-25-servicio-igss-2020-23\/","title":{"rendered":"Reconocimiento 25 servicio IGSS 2020-23"},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-19909","attachment","type-attachment","status-inherit"],"description":{"rendered":"<p class=\"attachment\"><a href='\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-300x200.jpg 300w, \/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-768x512.jpg 768w, \/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-1024x682.jpg 1024w, \/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-630x420.jpg 630w, \/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-696x464.jpg 696w, \/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-1068x712.jpg 1068w, \/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-534x356.jpg 534w, \/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1280,"height":853,"file":"2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23.jpg","filesize":234071,"sizes":{"td_485x360":{"file":"Reconocimiento-25-servicio-IGSS-2020-23-485x360.jpg","width":485,"height":360,"filesize":35652,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-485x360.jpg"},"thumbnail":{"file":"Reconocimiento-25-servicio-IGSS-2020-23-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-150x150.jpg"},"medium":{"file":"Reconocimiento-25-servicio-IGSS-2020-23-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-300x200.jpg"},"medium_large":{"file":"Reconocimiento-25-servicio-IGSS-2020-23-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-768x512.jpg"},"large":{"file":"Reconocimiento-25-servicio-IGSS-2020-23-1024x682.jpg","width":1024,"height":682,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-1024x682.jpg"},"td_0x420":{"file":"Reconocimiento-25-servicio-IGSS-2020-23-630x420.jpg","width":630,"height":420,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-630x420.jpg"},"td_80x60":{"file":"Reconocimiento-25-servicio-IGSS-2020-23-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-80x60.jpg"},"td_218x150":{"file":"Reconocimiento-25-servicio-IGSS-2020-23-218x150.jpg","width":218,"height":150,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-218x150.jpg"},"td_324x400":{"file":"Reconocimiento-25-servicio-IGSS-2020-23-324x400.jpg","width":324,"height":400,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-324x400.jpg"},"td_696x0":{"file":"Reconocimiento-25-servicio-IGSS-2020-23-696x464.jpg","width":696,"height":464,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-696x464.jpg"},"td_1068x0":{"file":"Reconocimiento-25-servicio-IGSS-2020-23-1068x712.jpg","width":1068,"height":712,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-1068x712.jpg"},"td_100x70":{"file":"Reconocimiento-25-servicio-IGSS-2020-23-100x70.jpg","width":100,"height":70,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-100x70.jpg"},"td_265x198":{"file":"Reconocimiento-25-servicio-IGSS-2020-23-265x198.jpg","width":265,"height":198,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-265x198.jpg"},"td_324x160":{"file":"Reconocimiento-25-servicio-IGSS-2020-23-324x160.jpg","width":324,"height":160,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-324x160.jpg"},"td_324x235":{"file":"Reconocimiento-25-servicio-IGSS-2020-23-324x235.jpg","width":324,"height":235,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-324x235.jpg"},"td_356x220":{"file":"Reconocimiento-25-servicio-IGSS-2020-23-356x220.jpg","width":356,"height":220,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-356x220.jpg"},"td_356x364":{"file":"Reconocimiento-25-servicio-IGSS-2020-23-356x364.jpg","width":356,"height":364,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-356x364.jpg"},"td_533x261":{"file":"Reconocimiento-25-servicio-IGSS-2020-23-533x261.jpg","width":533,"height":261,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-533x261.jpg"},"td_534x462":{"file":"Reconocimiento-25-servicio-IGSS-2020-23-534x356.jpg","width":534,"height":356,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-534x356.jpg"},"td_696x385":{"file":"Reconocimiento-25-servicio-IGSS-2020-23-696x385.jpg","width":696,"height":385,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-696x385.jpg"},"td_741x486":{"file":"Reconocimiento-25-servicio-IGSS-2020-23-741x486.jpg","width":741,"height":486,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-741x486.jpg"},"td_1068x580":{"file":"Reconocimiento-25-servicio-IGSS-2020-23-1068x580.jpg","width":1068,"height":580,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-1068x580.jpg"},"carrusel-slider":{"file":"Reconocimiento-25-servicio-IGSS-2020-23-500x440.jpg","width":500,"height":440,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23-500x440.jpg"},"full":{"file":"Reconocimiento-25-servicio-IGSS-2020-23.jpg","width":1280,"height":853,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"\/wp-content\/uploads\/sites\/5\/2020\/10\/Reconocimiento-25-servicio-IGSS-2020-23.jpg","_links":{"self":[{"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/media\/19909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/comments?post=19909"}]}}