{"id":7669,"date":"2018-11-14T09:44:55","date_gmt":"2018-11-14T15:44:55","guid":{"rendered":"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018.jpg"},"modified":"2018-11-14T09:44:55","modified_gmt":"2018-11-14T15:44:55","slug":"mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018","status":"inherit","type":"attachment","link":"https:\/\/www.igssgt.org\/noticias\/mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018\/","title":{"rendered":"Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018"},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-7669","attachment","type-attachment","status-inherit"],"description":{"rendered":"<p class=\"attachment\"><a href='\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-300x300.jpg 300w, \/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-150x150.jpg 150w, \/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-768x769.jpg 768w, \/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-1024x1024.jpg 1024w, \/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-420x420.jpg 420w, \/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-696x697.jpg 696w, \/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-1068x1069.jpg 1068w, \/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-462x462.jpg 462w, \/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018.jpg 1117w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1117,"height":1118,"file":"2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018.jpg","filesize":234062,"sizes":{"thumbnail":{"file":"Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-150x150.jpg"},"medium":{"file":"Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-300x300.jpg"},"medium_large":{"file":"Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-768x769.jpg","width":768,"height":769,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-768x769.jpg"},"large":{"file":"Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-1024x1024.jpg","width":1024,"height":1024,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-1024x1024.jpg"},"td_0x420":{"file":"Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-420x420.jpg","width":420,"height":420,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-420x420.jpg"},"td_80x60":{"file":"Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-80x60.jpg"},"td_218x150":{"file":"Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-218x150.jpg","width":218,"height":150,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-218x150.jpg"},"td_324x400":{"file":"Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-324x400.jpg","width":324,"height":400,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-324x400.jpg"},"td_696x0":{"file":"Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-696x697.jpg","width":696,"height":697,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-696x697.jpg"},"td_1068x0":{"file":"Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-1068x1069.jpg","width":1068,"height":1069,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-1068x1069.jpg"},"td_100x70":{"file":"Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-100x70.jpg","width":100,"height":70,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-100x70.jpg"},"td_265x198":{"file":"Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-265x198.jpg","width":265,"height":198,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-265x198.jpg"},"td_324x160":{"file":"Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-324x160.jpg","width":324,"height":160,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-324x160.jpg"},"td_324x235":{"file":"Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-324x235.jpg","width":324,"height":235,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-324x235.jpg"},"td_356x220":{"file":"Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-356x220.jpg","width":356,"height":220,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-356x220.jpg"},"td_356x364":{"file":"Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-356x364.jpg","width":356,"height":364,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-356x364.jpg"},"td_533x261":{"file":"Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-533x261.jpg","width":533,"height":261,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-533x261.jpg"},"td_534x462":{"file":"Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-462x462.jpg","width":462,"height":462,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-462x462.jpg"},"td_696x385":{"file":"Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-696x385.jpg","width":696,"height":385,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-696x385.jpg"},"td_741x486":{"file":"Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-741x486.jpg","width":741,"height":486,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-741x486.jpg"},"td_1068x580":{"file":"Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-1068x580.jpg","width":1068,"height":580,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-1068x580.jpg"},"carrusel-slider":{"file":"Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-500x440.jpg","width":500,"height":440,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018-500x440.jpg"},"full":{"file":"Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018.jpg","width":1117,"height":1118,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"\/wp-content\/uploads\/sites\/5\/2018\/11\/Mapa-de-abastecimiento-de-medicamentos-al-14-de-noviembre-de-2018.jpg","_links":{"self":[{"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/media\/7669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/comments?post=7669"}]}}