{"id":8936,"date":"2019-03-08T17:02:21","date_gmt":"2019-03-08T23:02:21","guid":{"rendered":"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11.jpg"},"modified":"2019-03-08T17:02:21","modified_gmt":"2019-03-08T23:02:21","slug":"dia-internacional-de-la-mujer-igss-2019-11","status":"inherit","type":"attachment","link":"https:\/\/www.igssgt.org\/noticias\/dia-internacional-de-la-mujer-igss-2019-11\/","title":{"rendered":"Dia Internacional de la Mujer IGSS 2019-11"},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-8936","attachment","type-attachment","status-inherit"],"description":{"rendered":"<p class=\"attachment\"><a href='\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-300x169.jpg 300w, \/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-768x431.jpg 768w, \/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-1024x575.jpg 1024w, \/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-748x420.jpg 748w, \/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-696x391.jpg 696w, \/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-1068x600.jpg 1068w, \/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-534x300.jpg 534w, \/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1280,"height":719,"file":"2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11.jpg","filesize":94033,"sizes":{"thumbnail":{"file":"Dia-Internacional-de-la-Mujer-IGSS-2019-11-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-150x150.jpg"},"medium":{"file":"Dia-Internacional-de-la-Mujer-IGSS-2019-11-300x169.jpg","width":300,"height":169,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-300x169.jpg"},"medium_large":{"file":"Dia-Internacional-de-la-Mujer-IGSS-2019-11-768x431.jpg","width":768,"height":431,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-768x431.jpg"},"large":{"file":"Dia-Internacional-de-la-Mujer-IGSS-2019-11-1024x575.jpg","width":1024,"height":575,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-1024x575.jpg"},"td_0x420":{"file":"Dia-Internacional-de-la-Mujer-IGSS-2019-11-748x420.jpg","width":748,"height":420,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-748x420.jpg"},"td_80x60":{"file":"Dia-Internacional-de-la-Mujer-IGSS-2019-11-80x60.jpg","width":80,"height":60,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-80x60.jpg"},"td_218x150":{"file":"Dia-Internacional-de-la-Mujer-IGSS-2019-11-218x150.jpg","width":218,"height":150,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-218x150.jpg"},"td_324x400":{"file":"Dia-Internacional-de-la-Mujer-IGSS-2019-11-324x400.jpg","width":324,"height":400,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-324x400.jpg"},"td_696x0":{"file":"Dia-Internacional-de-la-Mujer-IGSS-2019-11-696x391.jpg","width":696,"height":391,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-696x391.jpg"},"td_1068x0":{"file":"Dia-Internacional-de-la-Mujer-IGSS-2019-11-1068x600.jpg","width":1068,"height":600,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-1068x600.jpg"},"td_100x70":{"file":"Dia-Internacional-de-la-Mujer-IGSS-2019-11-100x70.jpg","width":100,"height":70,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-100x70.jpg"},"td_265x198":{"file":"Dia-Internacional-de-la-Mujer-IGSS-2019-11-265x198.jpg","width":265,"height":198,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-265x198.jpg"},"td_324x160":{"file":"Dia-Internacional-de-la-Mujer-IGSS-2019-11-324x160.jpg","width":324,"height":160,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-324x160.jpg"},"td_324x235":{"file":"Dia-Internacional-de-la-Mujer-IGSS-2019-11-324x235.jpg","width":324,"height":235,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-324x235.jpg"},"td_356x220":{"file":"Dia-Internacional-de-la-Mujer-IGSS-2019-11-356x220.jpg","width":356,"height":220,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-356x220.jpg"},"td_356x364":{"file":"Dia-Internacional-de-la-Mujer-IGSS-2019-11-356x364.jpg","width":356,"height":364,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-356x364.jpg"},"td_533x261":{"file":"Dia-Internacional-de-la-Mujer-IGSS-2019-11-533x261.jpg","width":533,"height":261,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-533x261.jpg"},"td_534x462":{"file":"Dia-Internacional-de-la-Mujer-IGSS-2019-11-534x300.jpg","width":534,"height":300,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-534x300.jpg"},"td_696x385":{"file":"Dia-Internacional-de-la-Mujer-IGSS-2019-11-696x385.jpg","width":696,"height":385,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-696x385.jpg"},"td_741x486":{"file":"Dia-Internacional-de-la-Mujer-IGSS-2019-11-741x486.jpg","width":741,"height":486,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-741x486.jpg"},"td_1068x580":{"file":"Dia-Internacional-de-la-Mujer-IGSS-2019-11-1068x580.jpg","width":1068,"height":580,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-1068x580.jpg"},"carrusel-slider":{"file":"Dia-Internacional-de-la-Mujer-IGSS-2019-11-500x440.jpg","width":500,"height":440,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-500x440.jpg"},"td_485x360":{"file":"Dia-Internacional-de-la-Mujer-IGSS-2019-11-485x360.jpg","width":485,"height":360,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11-485x360.jpg"},"full":{"file":"Dia-Internacional-de-la-Mujer-IGSS-2019-11.jpg","width":1280,"height":719,"mime_type":"image\/jpeg","source_url":"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"\/wp-content\/uploads\/sites\/5\/2019\/03\/Dia-Internacional-de-la-Mujer-IGSS-2019-11.jpg","_links":{"self":[{"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/media\/8936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/comments?post=8936"}]}}