{"id":34268,"date":"2023-03-17T08:00:00","date_gmt":"2023-03-17T14:00:00","guid":{"rendered":"https:\/\/www.igssgt.org\/noticias\/?p=34268"},"modified":"2023-03-17T08:49:56","modified_gmt":"2023-03-17T14:49:56","slug":"hospital-general-de-enfermedades-y-la-cruz-roja-guatemalteca-realizan-jornada-de-donacion-de-sangre","status":"publish","type":"post","link":"https:\/\/www.igssgt.org\/noticias\/2023\/03\/17\/hospital-general-de-enfermedades-y-la-cruz-roja-guatemalteca-realizan-jornada-de-donacion-de-sangre\/","title":{"rendered":"Hospital General de Enfermedades y la Cruz Roja Guatemalteca realizan jornada de donaci\u00f3n de sangre"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Con el fin de concientizar a la poblaci\u00f3n sobre la importancia de salvar vidas a trav\u00e9s de la donaci\u00f3n de sangre, el personal del Banco de Sangre del Hospital General de Enfermedades, conjuntamente con la Cruz Roja Guatemalteca y atendiendo al llamado de Everise Guatemala, un call center con funcionamiento en la capital, realiz\u00f3 una jornada de donaci\u00f3n voluntaria.<\/p>\n\n\n<p><a href=\"\/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-3.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-34272 size-full\" src=\"\/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-3.jpg\" alt=\"\" width=\"1057\" height=\"1018\" srcset=\"\/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-3.jpg 1057w, \/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-3-300x289.jpg 300w, \/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-3-768x740.jpg 768w, \/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-3-1024x986.jpg 1024w, \/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-3-436x420.jpg 436w, \/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-3-696x670.jpg 696w, \/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-3-480x462.jpg 480w\" sizes=\"auto, (max-width: 1057px) 100vw, 1057px\" \/><\/a><\/p>\n<p>Desde las primeras horas de la ma\u00f1ana, j\u00f3venes entusiastas asistieron al llamado de solidaridad, por ello, la afluencia de personas super\u00f3 las expectativas.<\/p>\n<blockquote>\n<p>La mayor\u00eda de personas est\u00e1n aptas para donar, excepto aquellas que tienen bajo peso, sufren de diabetes, hipertensi\u00f3n, problemas hep\u00e1ticos, o est\u00e9n tomando antibi\u00f3ticos<\/p>\n<\/blockquote>\n<p>Beatriz Ayau manifest\u00f3 que la triste experiencia vivida con la p\u00e9rdida de un familiar, a quien fue imposible encontrarle donantes, fue el motivo para participar en la jornada, y aprovech\u00f3 la oportunidad para hacer el llamado a que m\u00e1s personas se sumen a este tipo de actividades altruistas. Por su parte Ilka Qui\u00f1\u00f3nez, supervisora del Banco de Sangre del IGSS de la zona 9, hizo referencia a la necesidad que se tiene de abastecer los centros de atenci\u00f3n m\u00e9dica a nivel nacional.<\/p>\n<p><a href=\"\/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-1.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-34270 size-full\" src=\"\/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-1.jpg\" alt=\"\" width=\"1200\" height=\"888\" srcset=\"\/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-1.jpg 1200w, \/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-1-485x360.jpg 485w, \/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-1-300x222.jpg 300w, \/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-1-768x568.jpg 768w, \/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-1-1024x758.jpg 1024w, \/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-1-568x420.jpg 568w, \/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-1-80x60.jpg 80w, \/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-1-696x515.jpg 696w, \/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-1-1068x790.jpg 1068w, \/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-1-534x395.jpg 534w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n<p>Adem\u00e1s, mencion\u00f3 que la mayor\u00eda de personas est\u00e1n aptas para donar, excepto aquellas que tienen bajo peso, sufren de alguna patolog\u00eda como diabetes, hipertensi\u00f3n, problemas hep\u00e1ticos, o bien est\u00e9n tomando alg\u00fan medicamento como antibi\u00f3ticos.<\/p>\n<p>El personal m\u00e9dico de la Cruz Roja Guatemalteca aplaudi\u00f3 la iniciativa de la campa\u00f1a e inst\u00f3 a la poblaci\u00f3n a perder el miedo a la donaci\u00f3n y a ser h\u00e9roes an\u00f3nimos.<\/p>\n<p><a href=\"\/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-4.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-34273 size-full\" src=\"\/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-4.jpg\" alt=\"\" width=\"1200\" height=\"854\" srcset=\"\/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-4.jpg 1200w, \/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-4-300x214.jpg 300w, \/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-4-768x547.jpg 768w, \/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-4-1024x729.jpg 1024w, \/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-4-590x420.jpg 590w, \/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-4-696x495.jpg 696w, \/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-4-1068x760.jpg 1068w, \/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-4-100x70.jpg 100w, \/wp-content\/uploads\/sites\/5\/2023\/03\/donacion-de-sangre-4-534x380.jpg 534w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el fin de concientizar a la poblaci\u00f3n sobre la importancia de salvar vidas a trav\u00e9s de la donaci\u00f3n de sangre, el personal del Banco de Sangre del Hospital General de Enfermedades, conjuntamente con la Cruz Roja Guatemalteca y atendiendo al llamado de Everise Guatemala, un call center con funcionamiento en la capital, realiz\u00f3 una [&hellip;]<\/p>\n","protected":false},"author":1961,"featured_media":34271,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[481,1227],"coauthors":[],"class_list":{"0":"post-34268","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad","8":"tag-hospital-general-de-enfermedades","9":"tag-jornada-de-donacion-de-sangre"},"_links":{"self":[{"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/posts\/34268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/users\/1961"}],"replies":[{"embeddable":true,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/comments?post=34268"}],"version-history":[{"count":5,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/posts\/34268\/revisions"}],"predecessor-version":[{"id":34277,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/posts\/34268\/revisions\/34277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/media\/34271"}],"wp:attachment":[{"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/media?parent=34268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/categories?post=34268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/tags?post=34268"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/coauthors?post=34268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}