{"id":36832,"date":"2023-07-24T09:08:34","date_gmt":"2023-07-24T15:08:34","guid":{"rendered":"https:\/\/www.igssgt.org\/noticias\/?p=36832"},"modified":"2023-07-24T09:09:25","modified_gmt":"2023-07-24T15:09:25","slug":"pacientes-de-camip-2-barranquilla-con-atencion-integral","status":"publish","type":"post","link":"https:\/\/www.igssgt.org\/noticias\/2023\/07\/24\/pacientes-de-camip-2-barranquilla-con-atencion-integral\/","title":{"rendered":"Pacientes de Camip 2 Barranquilla con atenci\u00f3n integral"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Los jubilados, pensionados y otros usuarios del Centro Atenci\u00f3n M\u00e9dico Integral para Pensionados CAMIP 2 Barranquilla participaron en las pausas activas que lleva a cabo el \u00e1rea de Fisioterapia con la finalidad de que se mantengan en movimiento durante su estad\u00eda en la Unidad.<\/p>\n\n\n\n<p>El coordinador del \u00e1rea, licenciado Jos\u00e9 Hern\u00e1ndez, coment\u00f3 que las pausas activas sirven para recuperar energ\u00eda, mejorar el desempe\u00f1o y eficiencia en el trabajo o quehaceres diarios, a trav\u00e9s de diferentes t\u00e9cnicas y ejercicios que ayudan a reducir la fatiga, disminuir trastornos musculo-esquel\u00e9ticos y prevenir el estr\u00e9s.<\/p>\n<p><a href=\"\/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-3.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-36836 size-full\" src=\"\/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-3.jpg\" alt=\"\" width=\"1600\" height=\"900\" srcset=\"\/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-3.jpg 1600w, \/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-3-300x169.jpg 300w, \/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-3-768x432.jpg 768w, \/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-3-1024x576.jpg 1024w, \/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-3-1536x864.jpg 1536w, \/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-3-747x420.jpg 747w, \/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-3-696x392.jpg 696w, \/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-3-1068x601.jpg 1068w, \/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-3-534x300.jpg 534w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/a><\/p>\n<p>Al mismo tiempo, lo que se busca con estos espacios es que los pacientes adultos realicen ejercicios b\u00e1sicos y funcionales de movilidad articular, estiramiento, fortalecimiento y relajaci\u00f3n, agreg\u00f3 Hern\u00e1ndez.<\/p>\n<blockquote>\n<p>Las pausas activas sirven para recuperar energ\u00eda, mejorar el desempe\u00f1o y eficiencia en el trabajo<\/p>\n<\/blockquote>\n<p><strong>\u201cEste tipo de ejercicios aumentan sus posibilidades de mejorar su salud, por supuesto, hay que ser constante y rutinario. Esta actividad no toma mucho tiempo, solo es cuesti\u00f3n de liberar un espacio en el d\u00eda para poder cumplir con los ejercicios que recomendamos\u201d<\/strong>, resalt\u00f3 el profesional.<\/p>\n<p><a href=\"\/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-4.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-36837 size-full\" src=\"\/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-4.jpg\" alt=\"\" width=\"1600\" height=\"900\" srcset=\"\/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-4.jpg 1600w, \/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-4-300x169.jpg 300w, \/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-4-768x432.jpg 768w, \/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-4-1024x576.jpg 1024w, \/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-4-1536x864.jpg 1536w, \/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-4-747x420.jpg 747w, \/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-4-696x392.jpg 696w, \/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-4-1068x601.jpg 1068w, \/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-4-534x300.jpg 534w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/a><\/p>\n<p>Beneficios de las pausas activas en adultos mayores:<\/p>\n<ul>\n<li>Ayuda a controlar los niveles de estr\u00e9s<\/li>\n<li>Evita la fatiga f\u00edsica y mental<\/li>\n<li>Previene los espasmos musculares<\/li>\n<li>Combate la baja productividad<\/li>\n<li>Aumenta la motivaci\u00f3n y el estado de \u00e1nimo<\/li>\n<\/ul>\n<p><a href=\"\/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-1.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-36838 size-full\" src=\"\/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-1.jpg\" alt=\"\" width=\"1600\" height=\"900\" srcset=\"\/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-1.jpg 1600w, \/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-1-300x169.jpg 300w, \/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-1-768x432.jpg 768w, \/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-1-1024x576.jpg 1024w, \/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-1-1536x864.jpg 1536w, \/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-1-747x420.jpg 747w, \/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-1-696x392.jpg 696w, \/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-1-1068x601.jpg 1068w, \/wp-content\/uploads\/sites\/5\/2023\/07\/Camip-2-Barranquilla-1-534x300.jpg 534w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los jubilados, pensionados y otros usuarios del Centro Atenci\u00f3n M\u00e9dico Integral para Pensionados CAMIP 2 Barranquilla participaron en las pausas activas que lleva a cabo el \u00e1rea de Fisioterapia con la finalidad de que se mantengan en movimiento durante su estad\u00eda en la Unidad. El coordinador del \u00e1rea, licenciado Jos\u00e9 Hern\u00e1ndez, coment\u00f3 que las pausas [&hellip;]<\/p>\n","protected":false},"author":1961,"featured_media":36835,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[1157,444],"coauthors":[],"class_list":{"0":"post-36832","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad","8":"tag-camip-2-barranquilla","9":"tag-fisioterapia"},"_links":{"self":[{"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/posts\/36832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/users\/1961"}],"replies":[{"embeddable":true,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/comments?post=36832"}],"version-history":[{"count":3,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/posts\/36832\/revisions"}],"predecessor-version":[{"id":36839,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/posts\/36832\/revisions\/36839"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/media\/36835"}],"wp:attachment":[{"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/media?parent=36832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/categories?post=36832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/tags?post=36832"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/coauthors?post=36832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}