{"id":53587,"date":"2026-01-29T14:30:00","date_gmt":"2026-01-29T20:30:00","guid":{"rendered":"https:\/\/www.igssgt.org\/noticias\/?p=53587"},"modified":"2026-02-09T12:00:11","modified_gmt":"2026-02-09T18:00:11","slug":"publinews-unidad-periferica-zona-once-igss-inaugura-mejoras-en-tecnologia-e-infraestructura","status":"publish","type":"post","link":"https:\/\/www.igssgt.org\/noticias\/2026\/01\/29\/publinews-unidad-periferica-zona-once-igss-inaugura-mejoras-en-tecnologia-e-infraestructura\/","title":{"rendered":"Publinews. Unidad Perif\u00e9rica Zona Once: IGSS inaugura mejoras en tecnolog\u00eda e infraestructura"},"content":{"rendered":"\n<p><em><strong>Por\u00a0M\u00f3nica Duarte<\/strong><\/em><\/p>\n\n\n\n<p>El Instituto Guatemalteco de Seguridad Social (IGSS) inaugur\u00f3 el proyecto de infraestructura y tecnolog\u00eda \u201cSalud que evoluciona\u201d en la Unidad Perif\u00e9rica Zona Once. Se trata de un nuevo Laboratorio Cl\u00ednico con tecnolog\u00eda \u00fanica en Latinoam\u00e9rica, una Cl\u00ednica de Atenci\u00f3n 24 Horas Pedi\u00e1trica, el Centro Transfusional y un Auditorio Modular.<\/p>\n\n\n<p class=\"c-paragraph\">La doctora Karla Mar\u00eda Gonz\u00e1lez, directora m\u00e9dica de la Unidad Perif\u00e9rica Zona Once, indic\u00f3 que el nuevo Laboratorio se convertir\u00e1 en el\u00a0primero de Latinoam\u00e9rica en utilizar equipo que automatiza sus funciones para procesar pruebas.\u00a0\u201cDurante la instalaci\u00f3n de los equipos, tuvimos visita de otros pa\u00edses que est\u00e1n tomando como referencia a la instituci\u00f3n\u201d, destac\u00f3.<\/p>\n<p class=\"c-paragraph\">En total se contar\u00e1n con 15 equipos con la\u00a0m\u00e1s alta tecnolog\u00eda que reducir\u00e1n hasta el 60% de tiempo para procesar pruebas.\u00a0Estos tienen la capacidad de procesar, por hora, 2 mil muestras de Qu\u00edmica, 1 mil muestras de Inmunolog\u00eda y 220 muestras de Hematolog\u00eda.<\/p>\n<p><\/p>\n<p>La unidad tambi\u00e9n est\u00e1 estrenando una\u00a0Cl\u00ednica de Atenci\u00f3n 24 Horas Pedi\u00e1trica, que evitar\u00e1 el traslado de los ni\u00f1os beneficiarios a la Emergencia Pedi\u00e1trica del Hospital General de Enfermedades. \u201cLa Unidad Perif\u00e9rica Zona Once se fortalece y reafirma su compromiso para un IGSS m\u00e1s moderno y en evoluci\u00f3n\u201d, resalt\u00f3 la Dra. Gonz\u00e1lez.<\/p>\n<p> <\/p>\n<p>Por su parte, el licenciado Jos\u00e9 Adolfo Flamenco Jau, presidente de la\u00a0Junta Directiva del IGSS, indic\u00f3 que con estos resultados se materializan los planes estrat\u00e9gicos\u00a0de la instituci\u00f3n. \u201cEstamos entregando un nuevo Seguro Social a la poblaci\u00f3n afiliada\u201d, resalt\u00f3.<\/p>\n<p> <\/p>\n<p>Las autoridades tambi\u00e9n inauguraron el Centro Transfusional, el primero a nivel institucional, el cual adoptar\u00e1 el sistema de centralizaci\u00f3n de procesos sugerido por el\u00a0Ministerio de Salud P\u00fablica y Asistencia Social. Tambi\u00e9n, se habilit\u00f3 el Auditorio Modular,\u00a0un espacio especial para que el personal se capacite y realice sus reuniones de trabajo.<\/p>\n<p> <\/p>\n<p>\u201cLo que est\u00e1 pasando en la Unidad Perif\u00e9rica Zona Once es verdaderamente hist\u00f3rico\u201d, resalt\u00f3 el doctor Francisco G\u00f3dinez, subgerente de Prestaciones en Salud, al indicar que no hay otro\u00a0laboratorio en la regi\u00f3n que se le iguale en modernizaci\u00f3n y proceso de muestras.<\/p>\n<p> <\/p>\n<p>\u201cEs un antes y despu\u00e9s no solo para esta unidad, sino para el Seguro Social en general\u201d, agreg\u00f3 G\u00f3dinez. Este proyecto\u00a0ser\u00e1 de beneficio para m\u00e1s de 350 mil pacientes\u00a0que acuden a la unidad al a\u00f1o.<\/p>\n<p> <\/p>\n<h4><strong>Fuente: Publinews<\/strong><\/h4>\n<p> <\/p>\n<p>Enlace: <a href=\"https:\/\/www.publinews.gt\/business\/2026\/01\/29\/unidad-periferica-zona-once-igss-inaugura-mejoras-en-tecnologia-e-infraestructura\/\">https:\/\/www.publinews.gt\/business\/2026\/01\/29\/unidad-periferica-zona-once-igss-inaugura-mejoras-en-tecnologia-e-infraestructura\/<\/a><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Por\u00a0M\u00f3nica Duarte El Instituto Guatemalteco de Seguridad Social (IGSS) inaugur\u00f3 el proyecto de infraestructura y tecnolog\u00eda \u201cSalud que evoluciona\u201d en la Unidad Perif\u00e9rica Zona Once. Se trata de un nuevo Laboratorio Cl\u00ednico con tecnolog\u00eda \u00fanica en Latinoam\u00e9rica, una Cl\u00ednica de Atenci\u00f3n 24 Horas Pedi\u00e1trica, el Centro Transfusional y un Auditorio Modular. La doctora Karla Mar\u00eda [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":53588,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,41],"tags":[954,737,1443],"coauthors":[881],"class_list":{"0":"post-53587","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad","8":"category-igss-en-los-medios","9":"tag-igss-en-los-medios","10":"tag-publinews","11":"tag-unidad-periferica-zona-11"},"_links":{"self":[{"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/posts\/53587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/comments?post=53587"}],"version-history":[{"count":2,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/posts\/53587\/revisions"}],"predecessor-version":[{"id":53590,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/posts\/53587\/revisions\/53590"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/media\/53588"}],"wp:attachment":[{"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/media?parent=53587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/categories?post=53587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/tags?post=53587"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.igssgt.org\/noticias\/wp-json\/wp\/v2\/coauthors?post=53587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}